{"id":7303,"date":"2023-11-07T10:23:20","date_gmt":"2023-11-07T09:23:20","guid":{"rendered":"https:\/\/www.alphacan.com\/?page_id=7303"},"modified":"2023-11-21T14:48:35","modified_gmt":"2023-11-21T13:48:35","slug":"economie-circulaire","status":"publish","type":"page","link":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/","title":{"rendered":"\u00c9conomie circulaire"},"content":{"rendered":"<p><strong>FDES &#8211; <\/strong><strong><em>Fiche de D\u00e9claration Environnementale et Sanitaire<\/em><\/strong><strong> des <\/strong><strong>produits de construction<\/strong><\/p>\n<p>Les FDES concernent les produits de construction et de d\u00e9coration des b\u00e2timents. Elles sont la carte d\u2019identit\u00e9 environnementale des produits, bas\u00e9es sur les r\u00e9sultats de son Analyse du Cycle de Vie (ACV), dans la perspective du calcul de la performance environnementale du b\u00e2timent.<\/p>\n<p><strong>Elaboration<\/strong><\/p>\n<p>Cette d\u00e9claration normalis\u00e9e est \u00e9tablie sous la responsabilit\u00e9 des fabricants ou syndicats professionnels du produit selon la norme NF EN 15804+A2, et v\u00e9rifi\u00e9es par tierce partie ind\u00e9pendante habilit\u00e9. Elle est ensuite publi\u00e9e sur la base de donn\u00e9es nationale environnementale INIES.<\/p>\n<p>Au niveau Europ\u00e9en, l\u2019appellation FDES est assimilable \u00e0 une EPD (Environmental Product Declaration) Une FDES est une EPD Europ\u00e9enne, compl\u00e9t\u00e9e par des informations sanitaires.<\/p>\n<p><strong>D\u00e9finition<\/strong><\/p>\n<p>Les FDES prennent en compte l\u2019ensemble du cycle de vie du produit, de l\u2019extraction des mati\u00e8res premi\u00e8res \u00e0 sa fin de vie, y compris ses \u00e9tapes de fabrication, les transports, la mise en \u0153uvre dans le b\u00e2timent, l\u2019usage m\u00eame du produit et son d\u00e9mant\u00e8lement. Elle comptabilise les consommations en ressources naturelles, \u00e9nerg\u00e9tiques et \u00e9ventuels d\u00e9chets \u00e0 recycler ou \u00e9liminer (27 indicateurs environnementaux b\u00e2timent)<\/p>\n<p><strong>Objectif<\/strong><\/p>\n<p>Le r\u00f4le principal des FDES est de fournir des informations quantitatives normalis\u00e9es et v\u00e9rifi\u00e9es par tierce partie, pour ajouter des crit\u00e8res de choix environnementaux et sanitaires, pris en compte dans la r\u00e8glementation RE2020 ou les op\u00e9rations b\u00e2timent lab\u00e9lis\u00e9s HQE.<\/p>\n<p>Elles constituent un outil unique pour l\u2019\u00e9valuation de la performance environnementale des b\u00e2timents.<\/p>\n<p>Un guide complet relatif \u00e0 la RE2020 est disponible sur le site gouvernemental RT-b\u00e2timent : <a href=\"https:\/\/rt-re-batiment.developpement-durable.gouv.fr\/re2020-r320.html\" target=\"_blank\" rel=\"noopener\">https:\/\/rt-re-batiment.developpement-durable.gouv.fr\/re2020-r320.html<\/a><\/p>\n<p><strong>Diff\u00e9rents types de FDES<\/strong><\/p>\n<ul>\n<li><strong>Les FDES par d\u00e9faut<\/strong><\/li>\n<\/ul>\n<p>Valeurs tabul\u00e9es, fix\u00e9es arbitrairement par le Minist\u00e8re en charge de la construction (DHUP) et d\u00e9crivant les composants courants du b\u00e2timent. Ces valeurs par d\u00e9faut sont tr\u00e8s d\u00e9favorables car en l\u2019absence de donn\u00e9e sp\u00e9cifique, elles int\u00e8grent des coefficients de s\u00e9curit\u00e9 afin de couvrir l\u2019incertitude sur la performance environnementale du produit install\u00e9.<\/p>\n<ul>\n<li><strong>Les\u00a0FDES collectives<\/strong><\/li>\n<\/ul>\n<p>R\u00e9alis\u00e9es sur un m\u00eame produit g\u00e9n\u00e9rique, fabriqu\u00e9 par plusieurs industriels.<\/p>\n<p>C\u2019est le cas des FDES fen\u00eatre PVC, \u00e9dit\u00e9es par l\u2019UFME et des FDES Fermetures PVC, \u00e9dit\u00e9es par le groupement ACTIBAIE (FMB) et l\u2019UFME. Ces FDES sont bas\u00e9es sur les donn\u00e9es moyennes d\u00e9clar\u00e9es par les adh\u00e9rents (gammistes &amp; assembleurs) de syndicats professionnels<\/p>\n<p>Pour les fen\u00eatres fabriqu\u00e9es \u00e0 l\u2019aide des profil\u00e9s du syst\u00e8me In&rsquo;Alpha 70 (PVC teint\u00e9 masse, PVC\/fibre de verre, PVC\/aluminium) ne rentrant pas dans le champ d\u2019application des FDES collectives syndicales, ALPHACAN a r\u00e9alis\u00e9 des FDES collectives sp\u00e9cifiques \u00e0 cette gamme, r\u00e9serv\u00e9es aux seuls clients assembleurs identifi\u00e9s dans la liste clients partenaires <a href=\"https:\/\/www.alphacan.com\/wp-content\/uploads\/2023\/11\/FDES-SYSTEME-ALPHACAN-INALPHA-70.pdf\" target=\"_blank\" rel=\"noopener\">ICI<\/a>.<\/p>\n<p><strong>Les\u00a0FDES individuelles<\/strong><\/p>\n<p>R\u00e9alis\u00e9e sur un produit fabriqu\u00e9 par un industriel identifi\u00e9. Cette d\u00e9marche est fond\u00e9e lorsqu\u2019un acteur se distingue par son mode de fabrication et\/ou par un produit tr\u00e8s sp\u00e9cifique.<\/p>\n<ul>\n<li>Toutes ces\u00a0FDES peuvent \u00eatre adapt\u00e9es au produit mis en \u0153uvre sur l\u2019ouvrage \u00e9valu\u00e9, par calcul \u00e0 l\u2019aide d\u2019un \u00ab\u00a0configurateur\u00a0\u00bb reprenant les valeurs de base d\u2019une FDES \u00ab\u00a0m\u00e8re\u00a0\u00bb<\/li>\n<\/ul>\n<p><strong>Principales informations contenues dans une FDES<\/strong><\/p>\n<ul>\n<li>Caract\u00e9ristiques du produit : constituants principaux (mati\u00e8res premi\u00e8res, \u00e9ventuelles substances dangereuses\u2026), produits compl\u00e9mentaires pour la mise en \u0153uvre, emballages, \u2026\u00a0<\/li>\n<li>l\u2019unit\u00e9 fonctionnelle du produit et sa dur\u00e9e de vie<\/li>\n<li>Profil environnemental : ensemble d\u2019indicateurs environnementaux calcul\u00e9s sur l\u2019ensemble du cycle de vie du produit et principalement l\u2019empreinte carbone d\u00e9finie par l\u2019indicateur de R\u00e9chauffement climatique (en kg \u00e9quivalent de CO2 \/UF) Ces valeurs sont rapport\u00e9es \u00e0 une unit\u00e9 fonctionnelle, de 1m\u00b2 pour la fen\u00eatre, de fa\u00e7on \u00e0 pouvoir \u00eatre int\u00e9gr\u00e9es dans les outils de calcul.<\/li>\n<li>Informations sant\u00e9 et confort d\u2019usage : contribution du produit \u00e0 la qualit\u00e9 sanitaire des espaces int\u00e9rieurs et de l\u2019eau, contribution \u00e0 la qualit\u00e9 de vie dans le b\u00e2timent (confort hygrothermique, acoustique, visuel et olfactif)<\/li>\n<li>Identit\u00e9 de l\u2019\u00e9metteur de la FDES.<\/li>\n<\/ul>\n<p><strong>FDES ALPHAPRO<\/strong><\/p>\n<p>En ce qui concerne les marques produits du groupe Alphapro, en temps qu\u2019adh\u00e9rent de l\u2019UFME, Alphacan\/Profialis utilisent les FDES collectives auxquelles nous avons contribu\u00e9 en communiquant nos fiches de donn\u00e9es d\u2019inventaires environnemental de nos produits.<\/p>\n<ul>\n<li>Fen\u00eatres et porte-fen\u00eatre PVC blanches ou claires L&gt;0.82 (beige, gris clair), \u00e9paisseur cumul\u00e9 de verre &lt;= 12 mm<\/li>\n<li>Fen\u00eatres et porte-fen\u00eatre PVC blanches ou claires L&gt;0.82 (beige, gris clair), \u00e9paisseur cumul\u00e9 de verre &gt; 12 mm<\/li>\n<li>Fen\u00eatres et porte-fen\u00eatre PVC fonc\u00e9es L&lt;0.82 (Plax\u00e9es ou laqu\u00e9es), \u00e9paisseur cumul\u00e9 de verre &lt;= 12 mm<\/li>\n<li>Fen\u00eatres et porte-fen\u00eatre PVC fonc\u00e9es L&lt;0.82 (Plax\u00e9es ou laqu\u00e9es), \u00e9paisseur cumul\u00e9 de verre &gt; 12 mm<\/li>\n<li>Volets roulants PVC \u00e0 commande manuelle (sangle, treuil, tirage directe, \u2026)<\/li>\n<li>Volets roulants PVC \u00e0 commande motoris\u00e9e<\/li>\n<li>Volets battants ou coulissants PVC<\/li>\n<li>Profil\u00e9s de d\u00e9coration PVC (bardage, clin, bandeau de rive, cl\u00f4ture)<\/li>\n<\/ul>\n<p>Lorsqu\u2019un produit est innovant, il ne rentre plus dans le cadre de validit\u00e9 de la FDES des produits g\u00e9n\u00e9riques et de ce fait doit pr\u00e9senter sa propre FDES sp\u00e9cifique, comme c\u2019est le cas de la gamme In\u2019Alpha de couleurs fonc\u00e9e dont le renforcement des profil\u00e9s est assur\u00e9 par des joncs en fibre de verre en remplacement de renfort m\u00e9tallique dans le\u00a0 produit g\u00e9n\u00e9rique<\/p>\n<ul>\n<li>Fen\u00eatres et porte-fen\u00eatre PVC In\u2019Alpha fibre de verre<\/li>\n<\/ul>\n<p>La valeur \u00a0\u00bb D&#8217;empreinte Carbone \u00ab\u00a0ou r\u00e9chauffement Climatique \u00a0\u00bb \u00e0 prendre en compte dans les outils de Calculs se trouve sur la Base INIES, lien d\u2019acc\u00e8s direct\u00a0:<\/p>\n<p><a href=\"https:\/\/www.inies.fr\/\" target=\"_blank\" rel=\"noopener\">Inies, les donn\u00e9es environnementales et sanitaires de r\u00e9f\u00e9rence pour le b\u00e2timent et la RE2020 &#8211; Inies<\/a><\/p>\n<p><strong>Guide d\u2019acces <\/strong><\/p>\n<p>La valeur \u00ab r\u00e9chauffement climatique\u00a0\u00bb \u00e0 prendre en compte, associ\u00e9e \u00e0 l&rsquo;unit\u00e9 fonctionnelle consid\u00e9r\u00e9e (dans notre cas la Fen\u00eatre), est affich\u00e9 apr\u00e8s avoir cliqu\u00e9 sur<\/p>\n<ul>\n<li>onglet \u00ab\u00a0Indicateurs\u00a0\u00bb &#8211; ligne \u00ab\u00a0r\u00e9chauffement climatique en kg.CO\u00b2.eq\u00a0\u00bb &#8211; colonne \u00ab\u00a0Total Cycle de vie\u00a0\u00bb<\/li>\n<\/ul>\n<p>Les fiches FDES compl\u00e8tes sont t\u00e9l\u00e9chargeables en pdf sous l\u2019onglet \u00ab\u00a0Document\u00a0\u00bb<\/p>\n<p><a href=\"https:\/\/www.alphacan.com\/wp-content\/uploads\/2023\/11\/correspondance-produits-FDES-Alphacan.pdf\" target=\"_blank\" rel=\"noopener\"><strong>&gt; Correspondance produit ALPHAPRO et sa FDES INIES<\/strong><\/a>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FDES &#8211; Fiche de D\u00e9claration Environnementale et Sanitaire des produits de construction Les FDES concernent les produits de construction et de d\u00e9coration des b\u00e2timents. Elles sont la carte d\u2019identit\u00e9 environnementale des produits, bas\u00e9es sur les r\u00e9sultats de son Analyse du Cycle de Vie (ACV), dans la perspective du calcul de la performance environnementale du b\u00e2timent. [&hellip;]<\/p>\n","protected":false},"author":500,"featured_media":7125,"parent":9,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7303","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9conomie circulaire &#8211; Alphacan<\/title>\n<meta name=\"description\" content=\"FDES - Fiche de D\u00e9claration Environnementale et Sanitaire des produits de construction Les FDES concernent les produits de construction et de d\u00e9coration\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9conomie circulaire &#8211; Alphacan\" \/>\n<meta property=\"og:description\" content=\"FDES - Fiche de D\u00e9claration Environnementale et Sanitaire des produits de construction Les FDES concernent les produits de construction et de d\u00e9coration\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Alphacan\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-21T13:48:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alphacan.com\/wp-content\/uploads\/2023\/02\/microsoftteams-image-1-e1676995277153.png\" \/>\n\t<meta property=\"og:image:width\" content=\"531\" \/>\n\t<meta property=\"og:image:height\" content=\"378\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/\",\"url\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/\",\"name\":\"\u00c9conomie circulaire &#8211; Alphacan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alphacan.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/microsoftteams-image-1-e1676995277153.png\",\"datePublished\":\"2023-11-07T09:23:20+00:00\",\"dateModified\":\"2023-11-21T13:48:35+00:00\",\"description\":\"FDES - Fiche de D\u00e9claration Environnementale et Sanitaire des produits de construction Les FDES concernent les produits de construction et de d\u00e9coration\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alphacan.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/microsoftteams-image-1-e1676995277153.png\",\"contentUrl\":\"https:\\\/\\\/www.alphacan.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/microsoftteams-image-1-e1676995277153.png\",\"width\":531,\"height\":378},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/economie-circulaire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expertise\",\"item\":\"https:\\\/\\\/www.alphacan.com\\\/fr\\\/expertise-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c9conomie circulaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alphacan.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.alphacan.com\\\/es\\\/\",\"name\":\"Alphacan\",\"description\":\"Concepteur Menuiseries\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alphacan.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9conomie circulaire &#8211; Alphacan","description":"FDES - Fiche de D\u00e9claration Environnementale et Sanitaire des produits de construction Les FDES concernent les produits de construction et de d\u00e9coration","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9conomie circulaire &#8211; Alphacan","og_description":"FDES - Fiche de D\u00e9claration Environnementale et Sanitaire des produits de construction Les FDES concernent les produits de construction et de d\u00e9coration","og_url":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/","og_site_name":"Alphacan","article_modified_time":"2023-11-21T13:48:35+00:00","og_image":[{"width":531,"height":378,"url":"https:\/\/www.alphacan.com\/wp-content\/uploads\/2023\/02\/microsoftteams-image-1-e1676995277153.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/","url":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/","name":"\u00c9conomie circulaire &#8211; Alphacan","isPartOf":{"@id":"https:\/\/www.alphacan.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/#primaryimage"},"image":{"@id":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alphacan.com\/wp-content\/uploads\/2023\/02\/microsoftteams-image-1-e1676995277153.png","datePublished":"2023-11-07T09:23:20+00:00","dateModified":"2023-11-21T13:48:35+00:00","description":"FDES - Fiche de D\u00e9claration Environnementale et Sanitaire des produits de construction Les FDES concernent les produits de construction et de d\u00e9coration","breadcrumb":{"@id":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/#primaryimage","url":"https:\/\/www.alphacan.com\/wp-content\/uploads\/2023\/02\/microsoftteams-image-1-e1676995277153.png","contentUrl":"https:\/\/www.alphacan.com\/wp-content\/uploads\/2023\/02\/microsoftteams-image-1-e1676995277153.png","width":531,"height":378},{"@type":"BreadcrumbList","@id":"https:\/\/www.alphacan.com\/fr\/expertise-2\/economie-circulaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.alphacan.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Expertise","item":"https:\/\/www.alphacan.com\/fr\/expertise-2\/"},{"@type":"ListItem","position":3,"name":"\u00c9conomie circulaire"}]},{"@type":"WebSite","@id":"https:\/\/www.alphacan.com\/es\/#website","url":"https:\/\/www.alphacan.com\/es\/","name":"Alphacan","description":"Concepteur Menuiseries","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alphacan.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/pages\/7303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/users\/500"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/comments?post=7303"}],"version-history":[{"count":5,"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/pages\/7303\/revisions"}],"predecessor-version":[{"id":7335,"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/pages\/7303\/revisions\/7335"}],"up":[{"embeddable":true,"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/pages\/9"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/media\/7125"}],"wp:attachment":[{"href":"https:\/\/www.alphacan.com\/fr\/wp-json\/wp\/v2\/media?parent=7303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}